{"id":30868,"date":"2019-09-06T11:49:42","date_gmt":"2019-09-06T09:49:42","guid":{"rendered":"https:\/\/www.metaltex.com\/?p=30868"},"modified":"2022-07-12T08:43:44","modified_gmt":"2022-07-12T06:43:44","slug":"lacqua-e-vita","status":"publish","type":"post","link":"https:\/\/www.metaltex.com\/it\/lacqua-e-vita\/","title":{"rendered":"\u201cMadzi ndi moyo\u201d: \u201cL\u2019acqua \u00e8 vita\u201d in Chichewa"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1352px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_2 1_2 fusion-flex-column\" style=\"--awb-padding-top:0px;--awb-padding-bottom:5%;--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:3.84%;--awb-margin-bottom-large:35px;--awb-spacing-left-large:3.84%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element\" style=\"--awb-margin-top:0px;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-1 hover-type-none\"><a href=\"https:\/\/www.metaltex.com\/wp-content\/uploads\/2022\/06\/ok_Water-is-life_-1.jpg\" class=\"fusion-lightbox\" data-rel=\"iLightbox[f5997a402c0edc48675]\" data-caption=\"The well built in Mabuwa, Malawi\" data-title=\"ok_Water is life_ 1\" title=\"ok_Water is life_ 1\"><img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/www.metaltex.com\/wp-content\/uploads\/2022\/06\/ok_Water-is-life_-1.jpg\" alt class=\"img-responsive wp-image-30879\" srcset=\"https:\/\/www.metaltex.com\/wp-content\/uploads\/2022\/06\/ok_Water-is-life_-1-200x200.jpg 200w, https:\/\/www.metaltex.com\/wp-content\/uploads\/2022\/06\/ok_Water-is-life_-1-400x400.jpg 400w, https:\/\/www.metaltex.com\/wp-content\/uploads\/2022\/06\/ok_Water-is-life_-1-600x600.jpg 600w, https:\/\/www.metaltex.com\/wp-content\/uploads\/2022\/06\/ok_Water-is-life_-1-800x800.jpg 800w, https:\/\/www.metaltex.com\/wp-content\/uploads\/2022\/06\/ok_Water-is-life_-1.jpg 1000w\" sizes=\"(max-width: 1024px) 100vw, (max-width: 640px) 100vw, 800px\" \/><\/a><\/span><\/div><div class=\"fusion-image-element\" style=\"--awb-margin-top:30px;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-2 hover-type-none\"><img decoding=\"async\" width=\"1333\" height=\"1000\" title=\"ok_Water is life_2\" src=\"https:\/\/www.metaltex.com\/wp-content\/uploads\/2022\/06\/ok_Water-is-life_2.jpg\" alt class=\"img-responsive wp-image-30885\" srcset=\"https:\/\/www.metaltex.com\/wp-content\/uploads\/2022\/06\/ok_Water-is-life_2-200x150.jpg 200w, https:\/\/www.metaltex.com\/wp-content\/uploads\/2022\/06\/ok_Water-is-life_2-400x300.jpg 400w, https:\/\/www.metaltex.com\/wp-content\/uploads\/2022\/06\/ok_Water-is-life_2-600x450.jpg 600w, https:\/\/www.metaltex.com\/wp-content\/uploads\/2022\/06\/ok_Water-is-life_2-800x600.jpg 800w, https:\/\/www.metaltex.com\/wp-content\/uploads\/2022\/06\/ok_Water-is-life_2-1200x900.jpg 1200w, https:\/\/www.metaltex.com\/wp-content\/uploads\/2022\/06\/ok_Water-is-life_2.jpg 1333w\" sizes=\"(max-width: 1024px) 100vw, (max-width: 640px) 100vw, 800px\" \/><\/span><\/div><div class=\"fusion-image-element\" style=\"--awb-margin-top:30px;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-3 hover-type-none\"><img decoding=\"async\" width=\"1333\" height=\"1000\" title=\"ok_Water is life_3\" src=\"https:\/\/www.metaltex.com\/wp-content\/uploads\/2022\/06\/ok_Water-is-life_3.jpg\" alt class=\"img-responsive wp-image-30891\" srcset=\"https:\/\/www.metaltex.com\/wp-content\/uploads\/2022\/06\/ok_Water-is-life_3-200x150.jpg 200w, https:\/\/www.metaltex.com\/wp-content\/uploads\/2022\/06\/ok_Water-is-life_3-400x300.jpg 400w, https:\/\/www.metaltex.com\/wp-content\/uploads\/2022\/06\/ok_Water-is-life_3-600x450.jpg 600w, https:\/\/www.metaltex.com\/wp-content\/uploads\/2022\/06\/ok_Water-is-life_3-800x600.jpg 800w, https:\/\/www.metaltex.com\/wp-content\/uploads\/2022\/06\/ok_Water-is-life_3-1200x900.jpg 1200w, https:\/\/www.metaltex.com\/wp-content\/uploads\/2022\/06\/ok_Water-is-life_3.jpg 1333w\" sizes=\"(max-width: 1024px) 100vw, (max-width: 640px) 100vw, 800px\" \/><\/span><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_2 1_2 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:3.84%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:3.84%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\" style=\"--awb-text-transform:none;\"><div>\n<p>La nostra collega Sara Fontana viaggia nel cuore dell\u2019Africa in nome della sua associazione, per portare l\u2019acqua a chi non ha la fortuna di averla a portata di mano.<\/p>\n<\/div>\n<div>\n<p>Sara, che lavora nel reparto Marketing Comunicazione di Metaltex in Svizzera, lo scorso mese di luglio ha fatto un viaggio di turismo sostenibile in Malawi, per assistere all\u2019inaugurazione del pozzo finanziato dalla associazione comasca\u00a0<a title=\"*Koin\u00e9\" href=\"https:\/\/www.koineolgiate.it\/\" target=\"_blank\" rel=\"noopener\">*Koin\u00e9<\/a>,\u00a0a cui appartiene e partecipa in maniera attiva dal 1995.<\/p>\n<\/div>\n<div>\n<p>Lo scorso anno\u00a0<a title=\"*Koin\u00e9\" href=\"https:\/\/www.koineolgiate.it\/\" target=\"_blank\" rel=\"noopener\">*Koin\u00e9<\/a>, insieme ad altre associazioni, ha organizzato una serie di eventi per raccogliere donazioni fino a raggiungere il necessario per la costruzione di un pozzo nel villaggio di Mabuwa, che ospita anche una scuola elementare con quasi 2.000 studenti.<\/p>\n<\/div>\n<div>\n<p>\u201cL\u2019inaugurazione di un pozzo \u00e8 una festa per tutto il villaggio\u201d, racconta Sara, \u201cma soprattutto per le donne e per i bambini, che sono gli incaricati dell\u2019approvvigionamento dell\u2019acqua. Invece di fare chilometri a piedi per raggiungere fonti spesso fangose e non potabili, hanno acqua pulita vicino a casa, garantita per tutto l\u2019anno\u201d.<\/p>\n<\/div>\n<div>\n<p>Lo scavo dei pozzi, insieme alla costruzione di scuole e di dispensari medici, fa parte del progetto di Sottosopra Onlus, fondata da David Pantaleoni (italo-malawiano) per realizzare piccoli ma costanti interventi nelle comunit\u00e0 locali, in continua collaborazione con i partner sul territorio.<\/p>\n<\/div>\n<div>\n<p>L\u2019associazione crede infatti che solo con un lavoro paziente si potranno garantire migliori condizioni economiche e sociali, e le esperienze di turismo sostenibile vengono organizzate proprio per accompagnare i visitatori nella scoperta della realt\u00e0 africana. Oltre a visitare i progetti, il viaggio prevede infatti safari nelle riserve naturali del Paese, qualche giorno sul lago Malawi (il terzo per estensione in Africa), escursioni in montagna e nelle piantagioni di t\u00e8 e pranzi in ristoranti tipici.<\/p>\n<\/div>\n<div><\/div>\n<div>\n<p><i>Per maggiori informazioni sul turismo sostenibile in Malawi visita<\/i><i>\u00a0<\/i><a title=\"https:\/\/sottosopramalawi.com\/\" href=\"https:\/\/sottosopramalawi.com\/\" target=\"_blank\" rel=\"noopener\"><i>https:\/\/sottosopramalawi.com\/<\/i><\/a><i><\/i><\/p>\n<\/div>\n<div>\n<p><a title=\"*Koin\u00e9\" href=\"https:\/\/www.koineolgiate.it\/\" target=\"_blank\" rel=\"noopener\"><i>*Koin\u00e9<\/i><\/a><a title=\"Koine\" href=\"https:\/\/www.koineolgiate.it\/news\/inaugurazione-pozzo-malawi\/\" target=\"_blank\" rel=\"noopener\"><i>,<\/i><\/a><i>\u00a0\u00e8 un\u2019associazione senza fini di lucro ad Olgiate Comasco. Sara gestisce l\u2019omonima bottega di commercio equo e solidale in Via Repubblica, 5.<\/i><\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La nostra collega Sara Fontana viaggia nel cuore dell\u2019Africa in nome della sua associazione, per portare l\u2019acqua a chi non ha la fortuna di averla a portata di mano. Sara, che lavora nel reparto Marketing Comunicazione di Metaltex in Svizzera, lo scorso mese di luglio ha fatto un viaggio di turismo sostenibile in Malawi, per assistere all\u2019inaugurazione&#8230;<\/p>\n","protected":false},"author":4,"featured_media":30879,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[329,702,224],"tags":[],"class_list":["post-30868","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-2019-it","category-malawi-it","category-posts-it"],"_links":{"self":[{"href":"https:\/\/www.metaltex.com\/it\/wp-json\/wp\/v2\/posts\/30868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.metaltex.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.metaltex.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.metaltex.com\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.metaltex.com\/it\/wp-json\/wp\/v2\/comments?post=30868"}],"version-history":[{"count":0,"href":"https:\/\/www.metaltex.com\/it\/wp-json\/wp\/v2\/posts\/30868\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.metaltex.com\/it\/wp-json\/wp\/v2\/media\/30879"}],"wp:attachment":[{"href":"https:\/\/www.metaltex.com\/it\/wp-json\/wp\/v2\/media?parent=30868"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.metaltex.com\/it\/wp-json\/wp\/v2\/categories?post=30868"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.metaltex.com\/it\/wp-json\/wp\/v2\/tags?post=30868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}